{"id":295424,"date":"2025-02-12T10:15:09","date_gmt":"2025-02-12T10:15:09","guid":{"rendered":"https:\/\/notisnot.com\/?post_type=product&#038;p=295424"},"modified":"2025-05-15T08:43:50","modified_gmt":"2025-05-15T08:43:50","slug":"sudadera-canda-para-hombre","status":"publish","type":"product","link":"http:\/\/notisnot.com\/es\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/","title":{"rendered":"Sudadera Canada para hombre"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-295425\" src=\"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115818-303x357.png\" alt=\"\" width=\"303\" height=\"357\" srcset=\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115818-303x357.png 303w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115818-505x595.png 505w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115818-10x12.png 10w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115818-17x20.png 17w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115818-600x707.png 600w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115818-91x107.png 91w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115818.png 754w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-295426\" src=\"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825-303x346.png\" alt=\"\" width=\"303\" height=\"346\" srcset=\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825-303x346.png 303w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825-505x577.png 505w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825-768x877.png 768w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825-11x12.png 11w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825-18x20.png 18w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825-600x685.png 600w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825-91x104.png 91w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825.png 781w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-295427\" src=\"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115835-303x366.png\" alt=\"\" width=\"303\" height=\"366\" srcset=\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115835-303x366.png 303w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115835-505x610.png 505w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115835-10x12.png 10w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115835-17x20.png 17w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115835-600x724.png 600w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115835-91x110.png 91w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115835.png 757w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-295428\" src=\"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115847-303x409.png\" alt=\"\" width=\"303\" height=\"409\" srcset=\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115847-303x409.png 303w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115847-505x682.png 505w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115847-9x12.png 9w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115847-15x20.png 15w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115847-600x810.png 600w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115847-91x123.png 91w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115847.png 699w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-295429\" src=\"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115857-303x414.png\" alt=\"\" width=\"303\" height=\"414\" srcset=\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115857-303x414.png 303w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115857-505x691.png 505w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115857-9x12.png 9w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115857-15x20.png 15w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115857-600x820.png 600w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115857-91x124.png 91w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115857.png 686w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-295430\" src=\"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115910-303x428.png\" alt=\"\" width=\"303\" height=\"428\" srcset=\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115910-303x428.png 303w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115910-505x714.png 505w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115910-8x12.png 8w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115910-14x20.png 14w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115910-600x848.png 600w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115910-91x129.png 91w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115910.png 627w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-295431\" src=\"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115918-303x344.png\" alt=\"\" width=\"303\" height=\"344\" srcset=\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115918-303x344.png 303w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115918-505x574.png 505w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115918-768x872.png 768w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115918-11x12.png 11w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115918-18x20.png 18w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115918-600x681.png 600w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115918-91x103.png 91w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115918.png 818w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-295432\" src=\"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115926-303x376.png\" alt=\"\" width=\"303\" height=\"376\" srcset=\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115926-303x376.png 303w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115926-505x626.png 505w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115926-10x12.png 10w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115926-16x20.png 16w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115926-600x744.png 600w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115926-91x113.png 91w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115926.png 697w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-295433\" src=\"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115932-303x410.png\" alt=\"\" width=\"303\" height=\"410\" srcset=\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115932-303x410.png 303w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115932-505x684.png 505w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115932-9x12.png 9w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115932-15x20.png 15w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115932-600x812.png 600w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115932-91x123.png 91w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115932.png 670w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-295434\" src=\"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115946-303x419.png\" alt=\"\" width=\"303\" height=\"419\" srcset=\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115946-303x419.png 303w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115946-505x698.png 505w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115946-9x12.png 9w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115946-14x20.png 14w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115946-600x829.png 600w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115946-91x126.png 91w, http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115946.png 689w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Sudadera para hombre, con media cremallera de pl\u00e1stico a juego y cursor met\u00e1lico, manga simple, pu\u00f1os y cintura de canal\u00e9 el\u00e1stico, costuras reforzadas.<\/p>\n<dl class=\"dl-horizontal dlpayper\"><\/dl>","protected":false},"featured_media":295426,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[272],"product_tag":[],"class_list":{"0":"post-295424","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-dessuadores-industria","7":"pa_color-azul-marino","8":"pa_color-azul-real","9":"pa_color-blanco","10":"pa_color-burdeos","11":"pa_color-humo","12":"pa_color-naranja","13":"pa_color-negro","14":"pa_color-rojo","15":"pa_color-verde","16":"pa_color-verde-gelatina","17":"pa_tallaropa-xs","18":"pa_tallaropa-s","19":"pa_tallaropa-m","20":"pa_tallaropa-l","21":"pa_tallaropa-xl","22":"pa_tallaropa-xxl","23":"pa_tallaropa-3xl","24":"pa_tallaropa-4xl","25":"pa_tallaropa-5xl","27":"first","28":"instock","29":"taxable","30":"shipping-taxable","31":"purchasable","32":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sudadera Canada para hombre - NOT IS NOT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/notisnot.com\/es\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sudadera Canada para hombre - NOT IS NOT\" \/>\n<meta property=\"og:description\" content=\"Sudadera para hombre, con media cremallera de pl\u00e1stico a juego y cursor met\u00e1lico, manga simple, pu\u00f1os y cintura de canal\u00e9 el\u00e1stico, costuras reforzadas.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/notisnot.com\/es\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/\" \/>\n<meta property=\"og:site_name\" content=\"NOT IS NOT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/notisnotofficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T08:43:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825.png\" \/>\n\t<meta property=\"og:image:width\" content=\"781\" \/>\n\t<meta property=\"og:image:height\" content=\"892\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/\",\"url\":\"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/\",\"name\":\"Sudadera Canada para hombre - NOT IS NOT\",\"isPartOf\":{\"@id\":\"https:\/\/notisnot.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825.png\",\"datePublished\":\"2025-02-12T10:15:09+00:00\",\"dateModified\":\"2025-05-15T08:43:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/#primaryimage\",\"url\":\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825.png\",\"contentUrl\":\"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825.png\",\"width\":781,\"height\":892},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/notisnot.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"http:\/\/notisnot.com\/es\/tienda-woocomerce\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sudadera Canada para hombre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/notisnot.com\/#website\",\"url\":\"https:\/\/notisnot.com\/\",\"name\":\"NOT IS NOT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/notisnot.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sudadera Canada para hombre - NOT IS NOT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/notisnot.com\/es\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/","og_locale":"es_ES","og_type":"article","og_title":"Sudadera Canada para hombre - NOT IS NOT","og_description":"Sudadera para hombre, con media cremallera de pl\u00e1stico a juego y cursor met\u00e1lico, manga simple, pu\u00f1os y cintura de canal\u00e9 el\u00e1stico, costuras reforzadas.","og_url":"http:\/\/notisnot.com\/es\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/","og_site_name":"NOT IS NOT","article_publisher":"https:\/\/www.facebook.com\/notisnotofficial\/","article_modified_time":"2025-05-15T08:43:50+00:00","og_image":[{"width":781,"height":892,"url":"https:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/","url":"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/","name":"Sudadera Canada para hombre - NOT IS NOT","isPartOf":{"@id":"https:\/\/notisnot.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/#primaryimage"},"image":{"@id":"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/#primaryimage"},"thumbnailUrl":"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825.png","datePublished":"2025-02-12T10:15:09+00:00","dateModified":"2025-05-15T08:43:50+00:00","breadcrumb":{"@id":"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/#primaryimage","url":"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825.png","contentUrl":"http:\/\/notisnot.com\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-11-115825.png","width":781,"height":892},{"@type":"BreadcrumbList","@id":"https:\/\/notisnot.com\/tienda\/ropa-laboral\/industria\/dessuadores-industria\/sudadera-canda-para-hombre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/notisnot.com\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"http:\/\/notisnot.com\/es\/tienda-woocomerce\/"},{"@type":"ListItem","position":3,"name":"Sudadera Canada para hombre"}]},{"@type":"WebSite","@id":"https:\/\/notisnot.com\/#website","url":"https:\/\/notisnot.com\/","name":"NOT IS NOT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/notisnot.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"http:\/\/notisnot.com\/es\/wp-json\/wp\/v2\/product\/295424"}],"collection":[{"href":"http:\/\/notisnot.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/notisnot.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"http:\/\/notisnot.com\/es\/wp-json\/wp\/v2\/comments?post=295424"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/notisnot.com\/es\/wp-json\/wp\/v2\/media\/295426"}],"wp:attachment":[{"href":"http:\/\/notisnot.com\/es\/wp-json\/wp\/v2\/media?parent=295424"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/notisnot.com\/es\/wp-json\/wp\/v2\/product_cat?post=295424"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/notisnot.com\/es\/wp-json\/wp\/v2\/product_tag?post=295424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}